{"id":1126,"count":1,"description":"","link":"https:\/\/englishbookgeorgia.com\/blogebg\/tag\/good-news\/","name":"good news","slug":"good-news","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/englishbookgeorgia.com\/blogebg\/wp-json\/wp\/v2\/tags\/1126","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/englishbookgeorgia.com\/blogebg\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/englishbookgeorgia.com\/blogebg\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/englishbookgeorgia.com\/blogebg\/wp-json\/wp\/v2\/posts?tags=1126"},{"href":"https:\/\/englishbookgeorgia.com\/blogebg\/wp-json\/wp\/v2\/pages?tags=1126"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}